{"id":1340,"date":"2024-05-14T12:34:55","date_gmt":"2024-05-14T15:34:55","guid":{"rendered":"https:\/\/camisetasebrindesexpress.com.br\/?post_type=product&#038;p=1340"},"modified":"2024-05-14T12:34:55","modified_gmt":"2024-05-14T15:34:55","slug":"31011-wave-cc-esferografica-com-acabamento-brilhante-e-tinta-dokumental","status":"publish","type":"product","link":"https:\/\/camisetasebrindesexpress.com.br\/index.php\/produto\/31011-wave-cc-esferografica-com-acabamento-brilhante-e-tinta-dokumental\/","title":{"rendered":"31011 WAVE CC. Esferogr\u00e1fica com acabamento brilhante e tinta Dokumental\u00ae"},"content":{"rendered":"<div class=\"texto\">Esferogr\u00e1fica com acabamento brilhante e tinta Dokumental\u00ae at\u00e9 2 km de escrita. Produto certificado de acordo com a portaria Inmetro n\u00ba423 de 8\/out\/2021. \u00f89 x 140 mm<\/div>\n<div class=\"icons\">\n<div class=\"icon\"><img decoding=\"async\" src=\"https:\/\/www.spotgifts.com.br\/fotos\/pictogramas\/escrita_azul_1140046434610cfc6d6c097.png\" alt=\"SPOT\" \/><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Esferogr\u00e1fica com acabamento brilhante e tinta Dokumental\u00ae at\u00e9 2 km de escrita. Produto certificado de acordo com a portaria Inmetro n\u00ba423 de 8\/out\/2021. \u00f89 x 140 mm<\/p>\n","protected":false},"featured_media":1346,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[20],"product_tag":[],"_links":{"self":[{"href":"https:\/\/camisetasebrindesexpress.com.br\/index.php\/wp-json\/wp\/v2\/product\/1340"}],"collection":[{"href":"https:\/\/camisetasebrindesexpress.com.br\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/camisetasebrindesexpress.com.br\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/camisetasebrindesexpress.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1340"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/camisetasebrindesexpress.com.br\/index.php\/wp-json\/wp\/v2\/media\/1346"}],"wp:attachment":[{"href":"https:\/\/camisetasebrindesexpress.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1340"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/camisetasebrindesexpress.com.br\/index.php\/wp-json\/wp\/v2\/product_cat?post=1340"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/camisetasebrindesexpress.com.br\/index.php\/wp-json\/wp\/v2\/product_tag?post=1340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}